{"id":5586,"date":"2025-11-25T22:48:04","date_gmt":"2025-11-25T21:48:04","guid":{"rendered":"https:\/\/aequus.fr\/journaldebord\/?p=5586"},"modified":"2025-11-29T14:50:09","modified_gmt":"2025-11-29T13:50:09","slug":"piege-a","status":"publish","type":"post","link":"https:\/\/aequus.fr\/journaldebord\/piege-a\/","title":{"rendered":"Pi\u00e8ge \u00e0 \u2026"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/aequus.fr\/journaldebord\/wp-content\/uploads\/IMG_3502-1024x768.jpeg\" alt=\"\" class=\"wp-image-5587\" srcset=\"https:\/\/aequus.fr\/journaldebord\/wp-content\/uploads\/IMG_3502-1024x768.jpeg 1024w, https:\/\/aequus.fr\/journaldebord\/wp-content\/uploads\/IMG_3502-300x225.jpeg 300w, https:\/\/aequus.fr\/journaldebord\/wp-content\/uploads\/IMG_3502-768x576.jpeg 768w, https:\/\/aequus.fr\/journaldebord\/wp-content\/uploads\/IMG_3502-1536x1151.jpeg 1536w, https:\/\/aequus.fr\/journaldebord\/wp-content\/uploads\/IMG_3502-2048x1535.jpeg 2048w, https:\/\/aequus.fr\/journaldebord\/wp-content\/uploads\/IMG_3502-scaled.jpeg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Ah bah bravo.. le bip\u00e8de a voulu jouer au tarzan des pondoirs avec son pi\u00e8ge \u00e0 rats ! Elle nous a fait un combo gagnant avec une m\u00e9sange et une de ses propres poules qui, soyons honn\u00eates, n\u2019a pas invent\u00e9 l\u2019\u0153uf \u00e0 la coque\u2026 ni le fil \u00e0 couper l&rsquo;eau ti\u00e8de.<br>D\u2019un c\u00f4t\u00e9, on a la petite m\u00e9sange qui s&rsquo;interroge avec ses billes rondes: \u00ab mais meuf, j\u2019\u00e9tais juste venue grappiller deux graines bio, j\u2019ai pas sign\u00e9 pour la ge\u00f4le, moi ! \u00bb. De l\u2019autre, ta poule (Pouic-Pouic, pour ne pas la nommer parce qu\u2019elle a la frimousse de l\u2019emploi) qui fait \u00ab beut, beut, Beut \u00bb, en mode \u00ab je ne faisais que passer dans le coin pour r\u00e9cup\u00e9rer ma gamelle de vers de farine de la veille..\u00a0\u00bb<br>Et le bip\u00e8de, pendant ce temps, qui re\u00e7oit une alarme sur T\u00e9l\u00e9-Pouic-pouic\u2122 avec deux intrusions d\u00e9tect\u00e9es en un seul coup:<br>&#8211; Un suspect \u00e0 plumes bleues et jaunes (niveau de menace faible : son gazouillis incessant et la d\u00e9coration personnalis\u00e9e de ton balcon, de tes v\u00eatements, de ta terrasse\u2026)<br>&#8211; Un suspect \u00e0 plumes noires (niveau de menace moyen : il te monte sur les genoux pendant que tu nettoies son pondoir ou te pique ta place dans le canap\u00e9 du salon.)<br>Moralit\u00e9 : le surmulot, lui, il est toujours au top et en divagation, il rigole en famille sous le poulailler, en sirotant son mojito-sainfoin. Il a m\u00eame pr\u00e9vu de poster une story sur Rat-stagram : \u00ab Quand les bip\u00e8des essaient de nous capturer mais pi\u00e8gent leur propre basse-cour \ud83d\ude02\ud83d\udc00 \u00bb<br>La prochaine fois, il serait pr\u00e9f\u00e9rable de demander plut\u00f4t de l&rsquo;aide aux chats. Eux au moins, ils seront capables de faire le distinguo entre un rat, une m\u00e9sange et une poule\u2026<br>Kandide<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":7,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1397,38],"tags":[1402,1399,1403,1398,1400,1401],"class_list":["post-5586","post","type-post","status-publish","format-standard","hentry","category-poules-et-compagnie","category-uvdc","tag-mesange","tag-piege-a-rats","tag-poule-bantame","tag-rats","tag-tele-poules","tag-video"],"acf":[],"_links":{"self":[{"href":"https:\/\/aequus.fr\/journaldebord\/wp-json\/wp\/v2\/posts\/5586","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aequus.fr\/journaldebord\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aequus.fr\/journaldebord\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aequus.fr\/journaldebord\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/aequus.fr\/journaldebord\/wp-json\/wp\/v2\/comments?post=5586"}],"version-history":[{"count":0,"href":"https:\/\/aequus.fr\/journaldebord\/wp-json\/wp\/v2\/posts\/5586\/revisions"}],"wp:attachment":[{"href":"https:\/\/aequus.fr\/journaldebord\/wp-json\/wp\/v2\/media?parent=5586"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aequus.fr\/journaldebord\/wp-json\/wp\/v2\/categories?post=5586"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aequus.fr\/journaldebord\/wp-json\/wp\/v2\/tags?post=5586"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}